{"id":22357,"date":"2020-10-15T12:16:12","date_gmt":"2020-10-15T12:16:12","guid":{"rendered":"https:\/\/homecareinnovation.com\/product\/la-alfombra-de-rayos-x\/"},"modified":"2020-10-15T12:16:12","modified_gmt":"2020-10-15T12:16:12","slug":"la-alfombra-de-rayos-x","status":"publish","type":"product","link":"https:\/\/homecareinnovation.com\/es\/producto\/la-alfombra-de-rayos-x\/","title":{"rendered":"La alfombra de rayos X"},"content":{"rendered":"<p><strong>Mate de rayos X:<\/strong><\/p>\n<p>El tapete de rayos X est\u00e1 especialmente dise\u00f1ado como soporte de la mesa de rayos X para el almacenamiento y posicionamiento seguro de los pacientes durante los ex\u00e1menes de rayos X. La c\u00f3moda superficie y el acolchado proporcionan al paciente un c\u00f3modo coj\u00edn. Usando las dos tiras de agarre en el lado de la colchoneta, la colchoneta se puede mover hacia atr\u00e1s y puede ser colocada con precisi\u00f3n por una o m\u00e1s enfermeras a la vez. La superficie es ligera, f\u00e1cil de desinfectar e impermeable al agua. El material de la alfombra de rayos X est\u00e1 completamente bloqueado por las ondas de radio.<\/p>\n<p>La alfombra de rayos X est\u00e1 disponible en dos anchos diferentes &#8211; como 60 cm de ancho (4500020) o como la versi\u00f3n de 85 cm de ancho (4500019).<\/p>\n<p>ADVERTENCIA: Por favor, tenga en cuenta que si usted tiene una radiograf\u00eda que va m\u00e1s all\u00e1 de las manijas de la alfombra, la costura de procesamiento de las manijas en el lado de la alfombra puede ser visible.<\/p>\n<p><strong>Material: <\/strong>PVC\/Nylon &#8211; Libre de l\u00e1tex<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Mate de rayos X:<\/strong><\/p>\n<p>El tapete de rayos X est\u00e1 especialmente dise\u00f1ado como soporte de la mesa de rayos X para el almacenamiento y posicionamiento seguro de los pacientes durante los ex\u00e1menes de rayos X. La c\u00f3moda superficie y el acolchado proporcionan al paciente un c\u00f3modo coj\u00edn. Usando las dos tiras de agarre en el lado de la colchoneta, la colchoneta se puede mover hacia atr\u00e1s y puede ser colocada con precisi\u00f3n por una o m\u00e1s enfermeras a la vez. La superficie es ligera, f\u00e1cil de desinfectar e impermeable al agua. El material de la alfombra de rayos X est\u00e1 completamente bloqueado por las ondas de radio.<\/p>\n<p>La alfombra de rayos X est\u00e1 disponible en dos anchos diferentes &#8211; como 60 cm de ancho (4500020) o como la versi\u00f3n de 85 cm de ancho (4500019).<\/p>\n<p> ADVERTENCIA: Por favor, tenga en cuenta que si usted tiene una radiograf\u00eda que va m\u00e1s all\u00e1 de las manijas de la alfombra, la costura de procesamiento de las manijas en el lado de la alfombra puede ser visible.<\/p>\n<p><strong>Material: <\/strong>PVC\/Nylon &#8211; Libre de l\u00e1tex<\/p>\n","protected":false},"featured_media":22358,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1325],"product_tag":[],"class_list":["post-22357","product","type-product","status-publish","has-post-thumbnail","product_cat-ayudas-para-la-transferencia","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La alfombra de rayos X - HomeCare Innovation BV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/homecareinnovation.com\/es\/producto\/la-alfombra-de-rayos-x\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La alfombra de rayos X - HomeCare Innovation BV\" \/>\n<meta property=\"og:description\" content=\"Mate de rayos X: El tapete de rayos X est\u00e1 especialmente dise\u00f1ado como soporte de la mesa de rayos X para el almacenamiento y posicionamiento seguro de los pacientes durante los ex\u00e1menes de rayos X. La c\u00f3moda superficie y el acolchado proporcionan al paciente un c\u00f3modo coj\u00edn. Usando las dos tiras de agarre en el lado de la colchoneta, la colchoneta se puede mover hacia atr\u00e1s y puede ser colocada con precisi\u00f3n por una o m\u00e1s enfermeras a la vez. La superficie es ligera, f\u00e1cil de desinfectar e impermeable al agua. El material de la alfombra de rayos X est\u00e1 completamente bloqueado por las ondas de radio. La alfombra de rayos X est\u00e1 disponible en dos anchos diferentes - como 60 cm de ancho (4500020) o como la versi\u00f3n de 85 cm de ancho (4500019).  ADVERTENCIA: Por favor, tenga en cuenta que si usted tiene una radiograf\u00eda que va m\u00e1s all\u00e1 de las manijas de la alfombra, la costura de procesamiento de las manijas en el lado de la alfombra puede ser visible. Material: PVC\/Nylon - Libre de l\u00e1tex\" \/>\n<meta property=\"og:url\" content=\"https:\/\/homecareinnovation.com\/es\/producto\/la-alfombra-de-rayos-x\/\" \/>\n<meta property=\"og:site_name\" content=\"HomeCare Innovation BV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HomeCareInnovationBV\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2020\/10\/4500019-4500020CuxAWvE9WbGYm.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1001\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/producto\\\/la-alfombra-de-rayos-x\\\/\",\"url\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/producto\\\/la-alfombra-de-rayos-x\\\/\",\"name\":\"La alfombra de rayos X - HomeCare Innovation BV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/producto\\\/la-alfombra-de-rayos-x\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/producto\\\/la-alfombra-de-rayos-x\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/homecareinnovation.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/4500019-4500020CuxAWvE9WbGYm.jpg\",\"datePublished\":\"2020-10-15T12:16:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/producto\\\/la-alfombra-de-rayos-x\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/producto\\\/la-alfombra-de-rayos-x\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/producto\\\/la-alfombra-de-rayos-x\\\/#primaryimage\",\"url\":\"https:\\\/\\\/homecareinnovation.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/4500019-4500020CuxAWvE9WbGYm.jpg\",\"contentUrl\":\"https:\\\/\\\/homecareinnovation.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/4500019-4500020CuxAWvE9WbGYm.jpg\",\"width\":1800,\"height\":1001},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/producto\\\/la-alfombra-de-rayos-x\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La alfombra de rayos X\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/\",\"name\":\"HomeCare Innovation BV\",\"description\":\"Mayorista de ayudas para ancianos y discapacitados\",\"publisher\":{\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/#organization\",\"name\":\"HomeCare Innovation BV\",\"url\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/homecareinnovation.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/HOME-CARE-LOGO-originele-kleur-klein.png\",\"contentUrl\":\"https:\\\/\\\/homecareinnovation.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/HOME-CARE-LOGO-originele-kleur-klein.png\",\"width\":1000,\"height\":357,\"caption\":\"HomeCare Innovation BV\"},\"image\":{\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HomeCareInnovationBV\\\/\",\"https:\\\/\\\/www.instagram.com\\\/homecareinnovation\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCg5pUSP6YEDGR5KtKeZe7nw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La alfombra de rayos X - HomeCare Innovation BV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/homecareinnovation.com\/es\/producto\/la-alfombra-de-rayos-x\/","og_locale":"es_ES","og_type":"article","og_title":"La alfombra de rayos X - HomeCare Innovation BV","og_description":"Mate de rayos X: El tapete de rayos X est\u00e1 especialmente dise\u00f1ado como soporte de la mesa de rayos X para el almacenamiento y posicionamiento seguro de los pacientes durante los ex\u00e1menes de rayos X. La c\u00f3moda superficie y el acolchado proporcionan al paciente un c\u00f3modo coj\u00edn. Usando las dos tiras de agarre en el lado de la colchoneta, la colchoneta se puede mover hacia atr\u00e1s y puede ser colocada con precisi\u00f3n por una o m\u00e1s enfermeras a la vez. La superficie es ligera, f\u00e1cil de desinfectar e impermeable al agua. El material de la alfombra de rayos X est\u00e1 completamente bloqueado por las ondas de radio. La alfombra de rayos X est\u00e1 disponible en dos anchos diferentes - como 60 cm de ancho (4500020) o como la versi\u00f3n de 85 cm de ancho (4500019).  ADVERTENCIA: Por favor, tenga en cuenta que si usted tiene una radiograf\u00eda que va m\u00e1s all\u00e1 de las manijas de la alfombra, la costura de procesamiento de las manijas en el lado de la alfombra puede ser visible. Material: PVC\/Nylon - Libre de l\u00e1tex","og_url":"https:\/\/homecareinnovation.com\/es\/producto\/la-alfombra-de-rayos-x\/","og_site_name":"HomeCare Innovation BV","article_publisher":"https:\/\/www.facebook.com\/HomeCareInnovationBV\/","og_image":[{"width":1800,"height":1001,"url":"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2020\/10\/4500019-4500020CuxAWvE9WbGYm.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/homecareinnovation.com\/es\/producto\/la-alfombra-de-rayos-x\/","url":"https:\/\/homecareinnovation.com\/es\/producto\/la-alfombra-de-rayos-x\/","name":"La alfombra de rayos X - HomeCare Innovation BV","isPartOf":{"@id":"https:\/\/homecareinnovation.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/homecareinnovation.com\/es\/producto\/la-alfombra-de-rayos-x\/#primaryimage"},"image":{"@id":"https:\/\/homecareinnovation.com\/es\/producto\/la-alfombra-de-rayos-x\/#primaryimage"},"thumbnailUrl":"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2020\/10\/4500019-4500020CuxAWvE9WbGYm.jpg","datePublished":"2020-10-15T12:16:12+00:00","breadcrumb":{"@id":"https:\/\/homecareinnovation.com\/es\/producto\/la-alfombra-de-rayos-x\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/homecareinnovation.com\/es\/producto\/la-alfombra-de-rayos-x\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/homecareinnovation.com\/es\/producto\/la-alfombra-de-rayos-x\/#primaryimage","url":"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2020\/10\/4500019-4500020CuxAWvE9WbGYm.jpg","contentUrl":"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2020\/10\/4500019-4500020CuxAWvE9WbGYm.jpg","width":1800,"height":1001},{"@type":"BreadcrumbList","@id":"https:\/\/homecareinnovation.com\/es\/producto\/la-alfombra-de-rayos-x\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/homecareinnovation.com\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/homecareinnovation.com\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"La alfombra de rayos X"}]},{"@type":"WebSite","@id":"https:\/\/homecareinnovation.com\/es\/#website","url":"https:\/\/homecareinnovation.com\/es\/","name":"HomeCare Innovation BV","description":"Mayorista de ayudas para ancianos y discapacitados","publisher":{"@id":"https:\/\/homecareinnovation.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/homecareinnovation.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/homecareinnovation.com\/es\/#organization","name":"HomeCare Innovation BV","url":"https:\/\/homecareinnovation.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/homecareinnovation.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2021\/03\/HOME-CARE-LOGO-originele-kleur-klein.png","contentUrl":"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2021\/03\/HOME-CARE-LOGO-originele-kleur-klein.png","width":1000,"height":357,"caption":"HomeCare Innovation BV"},"image":{"@id":"https:\/\/homecareinnovation.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HomeCareInnovationBV\/","https:\/\/www.instagram.com\/homecareinnovation\/","https:\/\/www.youtube.com\/channel\/UCg5pUSP6YEDGR5KtKeZe7nw"]}]}},"_links":{"self":[{"href":"https:\/\/homecareinnovation.com\/es\/wp-json\/wp\/v2\/product\/22357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homecareinnovation.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/homecareinnovation.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/homecareinnovation.com\/es\/wp-json\/wp\/v2\/comments?post=22357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/homecareinnovation.com\/es\/wp-json\/wp\/v2\/media\/22358"}],"wp:attachment":[{"href":"https:\/\/homecareinnovation.com\/es\/wp-json\/wp\/v2\/media?parent=22357"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/homecareinnovation.com\/es\/wp-json\/wp\/v2\/product_brand?post=22357"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/homecareinnovation.com\/es\/wp-json\/wp\/v2\/product_cat?post=22357"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/homecareinnovation.com\/es\/wp-json\/wp\/v2\/product_tag?post=22357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}