{"id":20021,"date":"2020-10-12T12:31:22","date_gmt":"2020-10-12T12:31:22","guid":{"rendered":"https:\/\/homecareinnovation.com\/product\/lente-di-ingrandimento-a-mani-libere\/"},"modified":"2020-10-12T12:31:22","modified_gmt":"2020-10-12T12:31:22","slug":"lente-di-ingrandimento-a-mani-libere","status":"publish","type":"product","link":"https:\/\/homecareinnovation.com\/it\/prodotto\/lente-di-ingrandimento-a-mani-libere\/","title":{"rendered":"Lente di ingrandimento a mani libere"},"content":{"rendered":"<p>Questa lente d&#8217;ingrandimento a mani libere \u00e8 stata progettata per le persone ipovedenti. E&#8217; a mani libere, quindi \u00e8 pi\u00f9 facile per voi.<\/p>\n<p>Con un interruttore on\/off incorporato leggero e facile da usare, la lente a mano libera con luce pu\u00f2 essere usata come lente a mano o a mani libere se usata in combinazione con il cavo da collo in dotazione, utile se si hanno mani deboli o tremolanti. Ideale per la lettura, il cucito o altre attivit\u00e0, questa lente d&#8217;ingrandimento beneficia di una grande lente acrilica di 105 mm di diametro e di un ingrandimento di 1,5 x.<\/p>\n<p><strong>Caratteristiche:<\/strong><\/p>\n<ul>\n<li>Ha anche una lente d&#8217;ingrandimento centrale 4 x per attivit\u00e0 ravvicinate o complicate.<\/li>\n<li>Adatto alla lettura e alla scrittura<\/li>\n<li>Vivavoce<\/li>\n<li>2 x batterie AAA<\/li>\n<li>Facile da pulire<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Questa lente d&#8217;ingrandimento a mani libere \u00e8 stata progettata per le persone ipovedenti. E&#8217; a mani libere, quindi \u00e8 pi\u00f9 facile per voi.<\/p>\n<p>Con un interruttore on\/off incorporato leggero e facile da usare, la lente a mano libera con luce pu\u00f2 essere usata come lente a mano o a mani libere se usata in combinazione con il cavo da collo in dotazione, utile se si hanno mani deboli o tremolanti. Ideale per la lettura, il cucito o altre attivit\u00e0, questa lente d&#8217;ingrandimento beneficia di una grande lente acrilica di 105 mm di diametro e di un ingrandimento di 1,5 x.<\/p>\n<p><strong>Caratteristiche:<\/strong><\/p>\n<ul>\n<li>Ha anche una lente d&#8217;ingrandimento centrale 4 x per attivit\u00e0 ravvicinate o complicate.<\/li>\n<li> Adatto alla lettura e alla scrittura<\/li>\n<li>Vivavoce<\/li>\n<li>2 x batterie AAA<\/li>\n<li>Facile da pulire<\/li>\n<\/ul>\n","protected":false},"featured_media":20022,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1171],"product_tag":[],"class_list":["post-20021","product","type-product","status-publish","has-post-thumbnail","product_cat-ausili-alla-lettura","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lente di ingrandimento a mani libere - HomeCare Innovation BV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/homecareinnovation.com\/it\/prodotto\/lente-di-ingrandimento-a-mani-libere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lente di ingrandimento a mani libere - HomeCare Innovation BV\" \/>\n<meta property=\"og:description\" content=\"Questa lente d&#039;ingrandimento a mani libere \u00e8 stata progettata per le persone ipovedenti. E&#039; a mani libere, quindi \u00e8 pi\u00f9 facile per voi. Con un interruttore on\/off incorporato leggero e facile da usare, la lente a mano libera con luce pu\u00f2 essere usata come lente a mano o a mani libere se usata in combinazione con il cavo da collo in dotazione, utile se si hanno mani deboli o tremolanti. Ideale per la lettura, il cucito o altre attivit\u00e0, questa lente d&#039;ingrandimento beneficia di una grande lente acrilica di 105 mm di diametro e di un ingrandimento di 1,5 x. Caratteristiche:  Ha anche una lente d&#039;ingrandimento centrale 4 x per attivit\u00e0 ravvicinate o complicate.  Adatto alla lettura e alla scrittura Vivavoce 2 x batterie AAA Facile da pulire\" \/>\n<meta property=\"og:url\" content=\"https:\/\/homecareinnovation.com\/it\/prodotto\/lente-di-ingrandimento-a-mani-libere\/\" \/>\n<meta property=\"og:site_name\" content=\"HomeCare Innovation BV\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HomeCareInnovationBV\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2020\/10\/l97093-1-hands-free-magnifier-with-light-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/prodotto\\\/lente-di-ingrandimento-a-mani-libere\\\/\",\"url\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/prodotto\\\/lente-di-ingrandimento-a-mani-libere\\\/\",\"name\":\"Lente di ingrandimento a mani libere - HomeCare Innovation BV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/prodotto\\\/lente-di-ingrandimento-a-mani-libere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/prodotto\\\/lente-di-ingrandimento-a-mani-libere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/homecareinnovation.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/l97093-1-hands-free-magnifier-with-light-1.jpg\",\"datePublished\":\"2020-10-12T12:31:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/prodotto\\\/lente-di-ingrandimento-a-mani-libere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/prodotto\\\/lente-di-ingrandimento-a-mani-libere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/prodotto\\\/lente-di-ingrandimento-a-mani-libere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/homecareinnovation.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/l97093-1-hands-free-magnifier-with-light-1.jpg\",\"contentUrl\":\"https:\\\/\\\/homecareinnovation.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/l97093-1-hands-free-magnifier-with-light-1.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/prodotto\\\/lente-di-ingrandimento-a-mani-libere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lente di ingrandimento a mani libere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/\",\"name\":\"HomeCare Innovation BV\",\"description\":\"Il grossista olandese di ausili medici\",\"publisher\":{\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/#organization\",\"name\":\"HomeCare Innovation BV\",\"url\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/homecareinnovation.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/HOME-CARE-LOGO-originele-kleur-klein.png\",\"contentUrl\":\"https:\\\/\\\/homecareinnovation.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/HOME-CARE-LOGO-originele-kleur-klein.png\",\"width\":1000,\"height\":357,\"caption\":\"HomeCare Innovation BV\"},\"image\":{\"@id\":\"https:\\\/\\\/homecareinnovation.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HomeCareInnovationBV\\\/\",\"https:\\\/\\\/www.instagram.com\\\/homecareinnovation\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCg5pUSP6YEDGR5KtKeZe7nw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lente di ingrandimento a mani libere - HomeCare Innovation BV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/homecareinnovation.com\/it\/prodotto\/lente-di-ingrandimento-a-mani-libere\/","og_locale":"it_IT","og_type":"article","og_title":"Lente di ingrandimento a mani libere - HomeCare Innovation BV","og_description":"Questa lente d'ingrandimento a mani libere \u00e8 stata progettata per le persone ipovedenti. E' a mani libere, quindi \u00e8 pi\u00f9 facile per voi. Con un interruttore on\/off incorporato leggero e facile da usare, la lente a mano libera con luce pu\u00f2 essere usata come lente a mano o a mani libere se usata in combinazione con il cavo da collo in dotazione, utile se si hanno mani deboli o tremolanti. Ideale per la lettura, il cucito o altre attivit\u00e0, questa lente d'ingrandimento beneficia di una grande lente acrilica di 105 mm di diametro e di un ingrandimento di 1,5 x. Caratteristiche:  Ha anche una lente d'ingrandimento centrale 4 x per attivit\u00e0 ravvicinate o complicate.  Adatto alla lettura e alla scrittura Vivavoce 2 x batterie AAA Facile da pulire","og_url":"https:\/\/homecareinnovation.com\/it\/prodotto\/lente-di-ingrandimento-a-mani-libere\/","og_site_name":"HomeCare Innovation BV","article_publisher":"https:\/\/www.facebook.com\/HomeCareInnovationBV\/","og_image":[{"width":1000,"height":1000,"url":"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2020\/10\/l97093-1-hands-free-magnifier-with-light-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/homecareinnovation.com\/it\/prodotto\/lente-di-ingrandimento-a-mani-libere\/","url":"https:\/\/homecareinnovation.com\/it\/prodotto\/lente-di-ingrandimento-a-mani-libere\/","name":"Lente di ingrandimento a mani libere - HomeCare Innovation BV","isPartOf":{"@id":"https:\/\/homecareinnovation.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/homecareinnovation.com\/it\/prodotto\/lente-di-ingrandimento-a-mani-libere\/#primaryimage"},"image":{"@id":"https:\/\/homecareinnovation.com\/it\/prodotto\/lente-di-ingrandimento-a-mani-libere\/#primaryimage"},"thumbnailUrl":"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2020\/10\/l97093-1-hands-free-magnifier-with-light-1.jpg","datePublished":"2020-10-12T12:31:22+00:00","breadcrumb":{"@id":"https:\/\/homecareinnovation.com\/it\/prodotto\/lente-di-ingrandimento-a-mani-libere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/homecareinnovation.com\/it\/prodotto\/lente-di-ingrandimento-a-mani-libere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/homecareinnovation.com\/it\/prodotto\/lente-di-ingrandimento-a-mani-libere\/#primaryimage","url":"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2020\/10\/l97093-1-hands-free-magnifier-with-light-1.jpg","contentUrl":"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2020\/10\/l97093-1-hands-free-magnifier-with-light-1.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/homecareinnovation.com\/it\/prodotto\/lente-di-ingrandimento-a-mani-libere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/homecareinnovation.com\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/homecareinnovation.com\/it\/shop\/"},{"@type":"ListItem","position":3,"name":"Lente di ingrandimento a mani libere"}]},{"@type":"WebSite","@id":"https:\/\/homecareinnovation.com\/it\/#website","url":"https:\/\/homecareinnovation.com\/it\/","name":"HomeCare Innovation BV","description":"Il grossista olandese di ausili medici","publisher":{"@id":"https:\/\/homecareinnovation.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/homecareinnovation.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/homecareinnovation.com\/it\/#organization","name":"HomeCare Innovation BV","url":"https:\/\/homecareinnovation.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/homecareinnovation.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2021\/03\/HOME-CARE-LOGO-originele-kleur-klein.png","contentUrl":"https:\/\/homecareinnovation.com\/wp-content\/uploads\/2021\/03\/HOME-CARE-LOGO-originele-kleur-klein.png","width":1000,"height":357,"caption":"HomeCare Innovation BV"},"image":{"@id":"https:\/\/homecareinnovation.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HomeCareInnovationBV\/","https:\/\/www.instagram.com\/homecareinnovation\/","https:\/\/www.youtube.com\/channel\/UCg5pUSP6YEDGR5KtKeZe7nw"]}]}},"_links":{"self":[{"href":"https:\/\/homecareinnovation.com\/it\/wp-json\/wp\/v2\/product\/20021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homecareinnovation.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/homecareinnovation.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/homecareinnovation.com\/it\/wp-json\/wp\/v2\/comments?post=20021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/homecareinnovation.com\/it\/wp-json\/wp\/v2\/media\/20022"}],"wp:attachment":[{"href":"https:\/\/homecareinnovation.com\/it\/wp-json\/wp\/v2\/media?parent=20021"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/homecareinnovation.com\/it\/wp-json\/wp\/v2\/product_brand?post=20021"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/homecareinnovation.com\/it\/wp-json\/wp\/v2\/product_cat?post=20021"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/homecareinnovation.com\/it\/wp-json\/wp\/v2\/product_tag?post=20021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}